{"id":143,"count":1,"description":"","link":"https:\/\/thetravlish.com\/journal\/tag\/swahili-heritage\/","name":"Swahili Heritage","slug":"swahili-heritage","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Swahili Heritage Archives - The Travlish Journal<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Swahili Heritage Archives - The Travlish Journal\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thetravlish.com\/journal\/tag\/swahili-heritage\/\" \/>\n<meta property=\"og:site_name\" content=\"The Travlish Journal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/thetravlish.com\\\/journal\\\/tag\\\/swahili-heritage\\\/\",\"url\":\"https:\\\/\\\/thetravlish.com\\\/journal\\\/tag\\\/swahili-heritage\\\/\",\"name\":\"Swahili Heritage Archives - The Travlish Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thetravlish.com\\\/journal\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thetravlish.com\\\/journal\\\/tag\\\/swahili-heritage\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thetravlish.com\\\/journal\\\/tag\\\/swahili-heritage\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thetravlish.com\\\/journal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Swahili Heritage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thetravlish.com\\\/journal\\\/#website\",\"url\":\"https:\\\/\\\/thetravlish.com\\\/journal\\\/\",\"name\":\"The Travlish Journal\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thetravlish.com\\\/journal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Swahili Heritage Archives - The Travlish Journal","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Swahili Heritage Archives - The Travlish Journal","og_url":"https:\/\/thetravlish.com\/journal\/tag\/swahili-heritage\/","og_site_name":"The Travlish Journal","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/thetravlish.com\/journal\/tag\/swahili-heritage\/","url":"https:\/\/thetravlish.com\/journal\/tag\/swahili-heritage\/","name":"Swahili Heritage Archives - The Travlish Journal","isPartOf":{"@id":"https:\/\/thetravlish.com\/journal\/#website"},"breadcrumb":{"@id":"https:\/\/thetravlish.com\/journal\/tag\/swahili-heritage\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/thetravlish.com\/journal\/tag\/swahili-heritage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thetravlish.com\/journal\/"},{"@type":"ListItem","position":2,"name":"Swahili Heritage"}]},{"@type":"WebSite","@id":"https:\/\/thetravlish.com\/journal\/#website","url":"https:\/\/thetravlish.com\/journal\/","name":"The Travlish Journal","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thetravlish.com\/journal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/thetravlish.com\/journal\/wp-json\/wp\/v2\/tags\/143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thetravlish.com\/journal\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/thetravlish.com\/journal\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/thetravlish.com\/journal\/wp-json\/wp\/v2\/posts?tags=143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}